{"id":28934,"date":"2024-07-26T16:06:18","date_gmt":"2024-07-26T19:06:18","guid":{"rendered":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/?p=28934"},"modified":"2024-07-26T16:49:29","modified_gmt":"2024-07-26T19:49:29","slug":"acordao-no-2352-2019","status":"publish","type":"post","link":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/acordao-no-2352-2019\/","title":{"rendered":"Ac\u00f3rd\u00e3o n\u00ba 2352\/2019"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>1108\u00aa Sess\u00e3o Ordin\u00e1ria, de 19\/03\/2019<\/li>\n\n\n\n<li>Processo: 030\/013236\/2018<\/li>\n\n\n\n<li>Recorrente: MAGNEPLAN ENGENHARIA LTDA<\/li>\n\n\n\n<li><strong>\u201cEmenta: IPTU \u2013 Recurso volunt\u00e1rio \u2013 Erro no procedimento \u2013 Peti\u00e7\u00e3o inicial que deve ser recebida como Pedido de Revis\u00e3o de Valor Venal \u2013 art. 129 e segts do PAT &#8211;&nbsp; A autoridade&nbsp; competente deve conferir prazo para que sejam sanadas irregularidades \u2013 art. 6,&nbsp; par\u00e1grafo 2\u00ba da Lei Municipal n\u00ba 3048\/13 e art. 11 par\u00e1grafo 2\u00ba do PAT \u2013 Provimento do recurso para anular a decis\u00e3o de primeira inst\u00e2ncia e remete o feito para an\u00e1lise do \u00f3rg\u00e3o competente.\u201d<\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Inteiro teor: <a href=\"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-content\/uploads\/2024\/07\/PA-013236.18-ESPELHO-010202.21-FLS.-41-A-77.pdf\">Ac\u00f3rd\u00e3o 2352\/2019<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>IPTU \u2013 Recurso volunt\u00e1rio \u2013 Erro no procedimento \u2013 Peti\u00e7\u00e3o inicial que deve ser recebida como Pedido de Revis\u00e3o de Valor Venal \u2013 art. 129 e segts do PAT &#8211;\u00a0 A autoridade\u00a0 competente deve conferir prazo para que sejam sanadas irregularidades \u2013 art. 6,\u00a0 par\u00e1grafo 2\u00ba da Lei Municipal n\u00ba 3048\/13 e art. 11 par\u00e1grafo 2\u00ba do PAT \u2013 Provimento do recurso para anular a decis\u00e3o de primeira inst\u00e2ncia e remete o feito para an\u00e1lise do \u00f3rg\u00e3o competente.\u201d<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_usar_header_alternativo":false,"footnotes":""},"categories":[131,126],"tags":[],"class_list":["post-28934","post","type-post","status-publish","format-standard","hentry","category-acordaos","category-ccn","et-doesnt-have-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/posts\/28934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/comments?post=28934"}],"version-history":[{"count":2,"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/posts\/28934\/revisions"}],"predecessor-version":[{"id":28941,"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/posts\/28934\/revisions\/28941"}],"wp:attachment":[{"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/media?parent=28934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/categories?post=28934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/tags?post=28934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}