{"id":29031,"date":"2024-07-29T12:51:47","date_gmt":"2024-07-29T15:51:47","guid":{"rendered":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/?p=29031"},"modified":"2024-07-29T13:04:59","modified_gmt":"2024-07-29T16:04:59","slug":"acordao-no-2371-2019","status":"publish","type":"post","link":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/acordao-no-2371-2019\/","title":{"rendered":"Ac\u00f3rd\u00e3o n\u00ba 2371\/2019"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong>1115\u00aa Sess\u00e3o Ordin\u00e1ria, de 07\/05\/2019<\/strong><\/li>\n\n\n\n<li><strong>Processo: 030\/0009426\/2018<\/strong><\/li>\n\n\n\n<li><strong>Recorrente: COMPANY LABORAT\u00d3RIO LTLDA<\/strong><\/li>\n\n\n\n<li><strong>\u201cEmenta: Aplica\u00e7\u00e3o retroativa da lei. A ratio essendi do art. 106 do CTN implica que as multas aplicadas por infra\u00e7\u00f5es administrativas tribut\u00e1rias devem seguir o princ\u00edpio da retroatividade da legisla\u00e7\u00e3o mais ben\u00e9fica vigente no momento da execu\u00e7\u00e3o, pelo que, independentemente de o fato gerador do tributo tenha ocorrido em data anterior a vig\u00eancia da norma sancionat\u00f3ria.\u201d<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Inteiro teor: <a href=\"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-content\/uploads\/2024\/07\/PA-09426.18.pdf\">Ac\u00f3rd\u00e3o 2371\/2019<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Aplica\u00e7\u00e3o retroativa da lei. A ratio essendi do art. 106 do CTN implica que as multas aplicadas por infra\u00e7\u00f5es administrativas tribut\u00e1rias devem seguir o princ\u00edpio da retroatividade da legisla\u00e7\u00e3o mais ben\u00e9fica vigente no momento da execu\u00e7\u00e3o, pelo que, independentemente de o fato gerador do tributo tenha ocorrido em data anterior a vig\u00eancia da norma sancionat\u00f3ria.\u201d<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_usar_header_alternativo":false,"footnotes":""},"categories":[131,126],"tags":[],"class_list":["post-29031","post","type-post","status-publish","format-standard","hentry","category-acordaos","category-ccn","et-doesnt-have-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/posts\/29031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/comments?post=29031"}],"version-history":[{"count":4,"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/posts\/29031\/revisions"}],"predecessor-version":[{"id":29044,"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/posts\/29031\/revisions\/29044"}],"wp:attachment":[{"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/media?parent=29031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/categories?post=29031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/tags?post=29031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}