{"id":8404,"date":"2019-12-09T14:18:19","date_gmt":"2019-12-09T17:18:19","guid":{"rendered":"https:\/\/fazenda.niteroi.rj.gov.br\/site\/?p=8404"},"modified":"2019-12-09T14:18:20","modified_gmt":"2019-12-09T17:18:20","slug":"acordao-1-744-2015","status":"publish","type":"post","link":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/acordao-1-744-2015\/","title":{"rendered":"Ac\u00f3rd\u00e3o 1.744\/2015"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li>834\u00ba Sess\u00e3o Ordin\u00e1ria, de 15\/10\/2015.<\/li><li>Processo: 030060494\/2011<\/li><li>Recorrente: Barcas S\/A &#8211; Transportes Mar\u00edtimos <\/li><li>Ementa: &#8220;Auto de Infra\u00e7\u00e3o lavrado com o objetivo de lan\u00e7ar ISS sobre opera\u00e7\u00f5es realizadas por terceiros n\u00e3o identificados, atribuindo-se responsabilidade tribut\u00e1ria ao tomador com base no disposto pelo ART. 58, inciso VIII, da lei n\u00b0. 480\/83. N\u00e3o identifica\u00e7\u00e3o dos tipos de servi\u00e7os prestados nem no relator do Auto e nem em sua base legal, prejudicando tanto a determina\u00e7\u00e3o da ocorr\u00eancia do fato gerador do imposto quanto a defesa do Recorrente. Recurso conhecido e provido em sentido contr\u00e1rio \u00e0 decis\u00e3o de Primeira Inst\u00e2ncia e pelo cancelamento do Auto de Infra\u00e7\u00e3o&#8221;.<\/li><li>Inteiro Teor: <a href=\"https:\/\/fazenda.niteroi.rj.gov.br\/site\/wp-content\/uploads\/2019\/12\/60494-11.pdf\">Ac\u00f3rd\u00e3o 1.744\/2015<\/a>; <\/li><li><strong>Enviado<\/strong> <strong>ao Prefeito para homologa\u00e7\u00e3o em: 20\/10\/2015.<\/strong><\/li><\/ul>\n\n\n\n<p>De acordo\ncom&nbsp; o que preceitua o Art. 86 Inciso II&nbsp; da Lei 3368\/18, que\nestabelece as decis\u00f5es do Conselho submetidas a ato homologat\u00f3rio do Prefeito\nMunicipal, precedido de manifesta\u00e7\u00e3o do Secret\u00e1rio de Fazenda. <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Data da Homologa\u00e7\u00e3o:  12\/11\/2018<\/strong><\/li><\/ul>\n\n\n\n<p>Conforme o arquivo que est\u00e1 no link a seguir: <a href=\"https:\/\/fazenda.niteroi.rj.gov.br\/site\/wp-content\/uploads\/2019\/12\/60494-11-HOMOL.pdf\">Decis\u00e3o do Prefeito em exerc\u00edcio do Munic\u00edpio de Niter\u00f3i.<\/a><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Publicado em Di\u00e1rio Oficial em 29\/12\/2018.<\/strong><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>834\u00ba Sess\u00e3o Ordin\u00e1ria, de 15\/10\/2015. Processo: 030060494\/2011 Recorrente: Barcas S\/A &#8211; Transportes Mar\u00edtimos Ementa: &#8220;Auto de Infra\u00e7\u00e3o lavrado com o objetivo de lan\u00e7ar ISS sobre opera\u00e7\u00f5es realizadas por terceiros n\u00e3o [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":911,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_usar_header_alternativo":false,"footnotes":""},"categories":[131,126],"tags":[],"class_list":["post-8404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acordaos","category-ccn","et-has-post-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/posts\/8404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/comments?post=8404"}],"version-history":[{"count":0,"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/posts\/8404\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/media\/911"}],"wp:attachment":[{"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/media?parent=8404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/categories?post=8404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fazenda.niteroi.rj.gov.br\/site\/wp-json\/wp\/v2\/tags?post=8404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}